{"id":68911,"date":"2024-12-02T23:44:06","date_gmt":"2024-12-02T23:44:06","guid":{"rendered":"https:\/\/inticash.com.pe\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/"},"modified":"2026-07-08T14:55:22","modified_gmt":"2026-07-08T14:55:22","slug":"pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro","status":"publish","type":"product","link":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/","title":{"rendered":"Pulsera para dama oro 18k Cartier 1&#215;1 con Colgantes Tematica Universo seguro Pico de loro"},"content":{"rendered":"<p>Pulsera para dama oro 18k Cartier 1&#215;1 con Colgantes Tematica Universo seguro Pico de loro<\/p>","protected":false},"excerpt":{"rendered":"<p>Pulsera para dama oro 18k Cartier 1&#215;1 con Colgantes Tematica Universo seguro Pico de loro<\/p>","protected":false},"featured_media":68909,"template":"","meta":[],"product_brand":[],"product_cat":[2608],"product_tag":[2604,2605],"class_list":["post-68911","product","type-product","status-publish","has-post-thumbnail","product_cat-pulsera-para-mujer","product_tag-06-arequipa","product_tag-centro","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Pulsera para dama oro 18k Cartier 1x1 con Colgantes Tematica Universo seguro Pico de loro\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Inticash - Joyer\u00eda, compramos y vendemos oro\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pulsera para dama oro 18k Cartier 1\u00d71 con Colgantes Tematica Universo seguro Pico de loro - Inticash\" \/>\n\t\t<meta property=\"og:description\" content=\"Pulsera para dama oro 18k Cartier 1x1 con Colgantes Tematica Universo seguro Pico de loro\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/inticash.com.pe.pe\/wp-content\/uploads\/2024\/10\/Joyerias-en-peru-oro-18k-imagen-metodos-de-pago.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/inticash.com.pe.pe\/wp-content\/uploads\/2024\/10\/Joyerias-en-peru-oro-18k-imagen-metodos-de-pago.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-12-02T23:44:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-08T14:55:22+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/InticashJoyeriaPeru\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pulsera para dama oro 18k Cartier 1\u00d71 con Colgantes Tematica Universo seguro Pico de loro - Inticash\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Pulsera para dama oro 18k Cartier 1x1 con Colgantes Tematica Universo seguro Pico de loro\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/inticash.com.pe.pe\/wp-content\/uploads\/2024\/10\/Joyerias-en-peru-oro-18k-imagen-metodos-de-pago.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/producto\\\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/inticash.com.pe\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/shop\\\/#listItem\",\"name\":\"Todos los productos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Todos los productos\",\"item\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/categoria-producto\\\/pulseras\\\/#listItem\",\"name\":\"Pulseras\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/categoria-producto\\\/pulseras\\\/#listItem\",\"position\":3,\"name\":\"Pulseras\",\"item\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/categoria-producto\\\/pulseras\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/categoria-producto\\\/pulseras\\\/pulsera-para-mujer\\\/#listItem\",\"name\":\"Pulsera para mujer\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/shop\\\/#listItem\",\"name\":\"Todos los productos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/categoria-producto\\\/pulseras\\\/pulsera-para-mujer\\\/#listItem\",\"position\":4,\"name\":\"Pulsera para mujer\",\"item\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/categoria-producto\\\/pulseras\\\/pulsera-para-mujer\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/producto\\\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\\\/#listItem\",\"name\":\"Pulsera para dama oro 18k Cartier 1&#215;1 con Colgantes Tematica Universo seguro Pico de loro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/categoria-producto\\\/pulseras\\\/#listItem\",\"name\":\"Pulseras\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/producto\\\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\\\/#listItem\",\"position\":5,\"name\":\"Pulsera para dama oro 18k Cartier 1&#215;1 con Colgantes Tematica Universo seguro Pico de loro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/categoria-producto\\\/pulseras\\\/pulsera-para-mujer\\\/#listItem\",\"name\":\"Pulsera para mujer\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/producto\\\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\\\/#itempage\",\"url\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/producto\\\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\\\/\",\"name\":\"Pulsera para dama oro 18k Cartier 1\\u00d71 con Colgantes Tematica Universo seguro Pico de loro - Inticash\",\"description\":\"Pulsera para dama oro 18k Cartier 1x1 con Colgantes Tematica Universo seguro Pico de loro\",\"inLanguage\":\"es-EC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/producto\\\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/inticash.com.pe\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/1Y2032408.19-scaled.jpg\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/producto\\\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\\\/#mainImage\",\"width\":2560,\"height\":2383},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/producto\\\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\\\/#mainImage\"},\"datePublished\":\"2024-12-02T23:44:06+00:00\",\"dateModified\":\"2026-07-08T14:55:22+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/#organization\",\"name\":\"Inticash Joyer\\u00eda\",\"description\":\"Joyer\\u00eda, compramos y vendemos oro Compramos y vendemos oro - Obt\\u00e9n dinero inmediato por tus joyas de oro\",\"url\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/\",\"telephone\":\"+51956251929\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/inticash.com.pe.pe\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/ISOTIPO-HD.png\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/producto\\\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/producto\\\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/InticashJoyeriaPeru\\\/\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/\",\"name\":\"Inticash Joyer\\u00eda - Compramos y Vendemos Oro\",\"description\":\"Joyer\\u00eda, compramos y vendemos oro\",\"inLanguage\":\"es-EC\",\"publisher\":{\"@id\":\"https:\\\/\\\/inticash.com.pe\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pulsera para dama oro 18k Cartier 1\u00d71 con Colgantes Tematica Universo seguro Pico de loro - Inticash","description":"Pulsera para dama oro 18k Cartier 1x1 con Colgantes Tematica Universo seguro Pico de loro","canonical_url":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es#listItem","position":1,"name":"Home","item":"https:\/\/inticash.com.pe\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es\/shop\/#listItem","name":"Todos los productos"}},{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es\/shop\/#listItem","position":2,"name":"Todos los productos","item":"https:\/\/inticash.com.pe\/es\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es\/categoria-producto\/pulseras\/#listItem","name":"Pulseras"},"previousItem":{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es\/categoria-producto\/pulseras\/#listItem","position":3,"name":"Pulseras","item":"https:\/\/inticash.com.pe\/es\/categoria-producto\/pulseras\/","nextItem":{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es\/categoria-producto\/pulseras\/pulsera-para-mujer\/#listItem","name":"Pulsera para mujer"},"previousItem":{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es\/shop\/#listItem","name":"Todos los productos"}},{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es\/categoria-producto\/pulseras\/pulsera-para-mujer\/#listItem","position":4,"name":"Pulsera para mujer","item":"https:\/\/inticash.com.pe\/es\/categoria-producto\/pulseras\/pulsera-para-mujer\/","nextItem":{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/#listItem","name":"Pulsera para dama oro 18k Cartier 1&#215;1 con Colgantes Tematica Universo seguro Pico de loro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es\/categoria-producto\/pulseras\/#listItem","name":"Pulseras"}},{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/#listItem","position":5,"name":"Pulsera para dama oro 18k Cartier 1&#215;1 con Colgantes Tematica Universo seguro Pico de loro","previousItem":{"@type":"ListItem","@id":"https:\/\/inticash.com.pe\/es\/categoria-producto\/pulseras\/pulsera-para-mujer\/#listItem","name":"Pulsera para mujer"}}]},{"@type":"ItemPage","@id":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/#itempage","url":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/","name":"Pulsera para dama oro 18k Cartier 1\u00d71 con Colgantes Tematica Universo seguro Pico de loro - Inticash","description":"Pulsera para dama oro 18k Cartier 1x1 con Colgantes Tematica Universo seguro Pico de loro","inLanguage":"es-EC","isPartOf":{"@id":"https:\/\/inticash.com.pe\/es\/#website"},"breadcrumb":{"@id":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/inticash.com.pe\/wp-content\/uploads\/2024\/12\/1Y2032408.19-scaled.jpg","@id":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/#mainImage","width":2560,"height":2383},"primaryImageOfPage":{"@id":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/#mainImage"},"datePublished":"2024-12-02T23:44:06+00:00","dateModified":"2026-07-08T14:55:22+00:00"},{"@type":"Organization","@id":"https:\/\/inticash.com.pe\/es\/#organization","name":"Inticash Joyer\u00eda","description":"Joyer\u00eda, compramos y vendemos oro Compramos y vendemos oro - Obt\u00e9n dinero inmediato por tus joyas de oro","url":"https:\/\/inticash.com.pe\/es\/","telephone":"+51956251929","logo":{"@type":"ImageObject","url":"https:\/\/inticash.com.pe.pe\/wp-content\/uploads\/2024\/10\/ISOTIPO-HD.png","@id":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/#organizationLogo"},"image":{"@id":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/InticashJoyeriaPeru\/"]},{"@type":"WebSite","@id":"https:\/\/inticash.com.pe\/es\/#website","url":"https:\/\/inticash.com.pe\/es\/","name":"Inticash Joyer\u00eda - Compramos y Vendemos Oro","description":"Joyer\u00eda, compramos y vendemos oro","inLanguage":"es-EC","publisher":{"@id":"https:\/\/inticash.com.pe\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Inticash - Joyer\u00eda, compramos y vendemos oro","og:type":"article","og:title":"Pulsera para dama oro 18k Cartier 1\u00d71 con Colgantes Tematica Universo seguro Pico de loro - Inticash","og:description":"Pulsera para dama oro 18k Cartier 1x1 con Colgantes Tematica Universo seguro Pico de loro","og:url":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/","og:image":"https:\/\/inticash.com.pe.pe\/wp-content\/uploads\/2024\/10\/Joyerias-en-peru-oro-18k-imagen-metodos-de-pago.jpg","og:image:secure_url":"https:\/\/inticash.com.pe.pe\/wp-content\/uploads\/2024\/10\/Joyerias-en-peru-oro-18k-imagen-metodos-de-pago.jpg","article:published_time":"2024-12-02T23:44:06+00:00","article:modified_time":"2026-07-08T14:55:22+00:00","article:publisher":"https:\/\/www.facebook.com\/InticashJoyeriaPeru\/","twitter:card":"summary_large_image","twitter:title":"Pulsera para dama oro 18k Cartier 1\u00d71 con Colgantes Tematica Universo seguro Pico de loro - Inticash","twitter:description":"Pulsera para dama oro 18k Cartier 1x1 con Colgantes Tematica Universo seguro Pico de loro","twitter:image":"https:\/\/inticash.com.pe.pe\/wp-content\/uploads\/2024\/10\/Joyerias-en-peru-oro-18k-imagen-metodos-de-pago.jpg"},"aioseo_meta_data":{"post_id":"68911","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-12-02 23:51:12","updated":"2026-07-08 14:59:44","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/inticash.com.pe\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/inticash.com.pe\/es\/shop\/\" title=\"Todos los productos\">Todos los productos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/inticash.com.pe\/es\/categoria-producto\/pulseras\/\" title=\"Pulseras\">Pulseras<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/inticash.com.pe\/es\/categoria-producto\/pulseras\/pulsera-para-mujer\/\" title=\"Pulsera para mujer\">Pulsera para mujer<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPulsera para dama oro 18k Cartier 1\u00d71 con Colgantes Tematica Universo seguro Pico de loro\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/inticash.com.pe\/es"},{"label":"Todos los productos","link":"https:\/\/inticash.com.pe\/es\/shop\/"},{"label":"Pulseras","link":"https:\/\/inticash.com.pe\/es\/categoria-producto\/pulseras\/"},{"label":"Pulsera para mujer","link":"https:\/\/inticash.com.pe\/es\/categoria-producto\/pulseras\/pulsera-para-mujer\/"},{"label":"Pulsera para dama oro 18k Cartier 1&#215;1 con Colgantes Tematica Universo seguro Pico de loro","link":"https:\/\/inticash.com.pe\/es\/producto\/pulsera-para-dama-oro-18k-cartier-1x1-con-colgantes-tematica-universo-seguro-pico-de-loro\/"}],"_links":{"self":[{"href":"https:\/\/inticash.com.pe\/es\/wp-json\/wp\/v2\/product\/68911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inticash.com.pe\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/inticash.com.pe\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inticash.com.pe\/es\/wp-json\/wp\/v2\/media\/68909"}],"wp:attachment":[{"href":"https:\/\/inticash.com.pe\/es\/wp-json\/wp\/v2\/media?parent=68911"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/inticash.com.pe\/es\/wp-json\/wp\/v2\/product_brand?post=68911"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/inticash.com.pe\/es\/wp-json\/wp\/v2\/product_cat?post=68911"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/inticash.com.pe\/es\/wp-json\/wp\/v2\/product_tag?post=68911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}